{"id":32428,"date":"2026-04-10T20:16:00","date_gmt":"2026-04-10T23:16:00","guid":{"rendered":"https:\/\/brasilsimulatormods.com\/?post_type=vehica_car&#038;p=32428"},"modified":"2026-04-10T20:16:02","modified_gmt":"2026-04-10T23:16:02","slug":"plymouth-gtx-hemi-gang-687-bros","status":"publish","type":"vehica_car","link":"https:\/\/brasilsimulatormods.com\/es\/puestos\/plymouth-gtx-hemi-gang-687-bros\/","title":{"rendered":"Plymouth GTX hemi Gang 687 Bros"},"content":{"rendered":"<p><strong>Uma verdadeira lenda do asfalto americano. Este Plymouth GTX combina a for\u00e7a bruta do motor V8 com o estilo cl\u00e1ssico das ruas, oferecendo uma experi\u00eancia de condu\u00e7\u00e3o visceral e nost\u00e1lgica.<\/strong><\/p>","protected":false},"author":1,"featured_media":32423,"template":"","vehica_23442":[2480],"vehica_6659":[2705],"vehica_6660":[4729],"vehica_6655":[2320],"vehica_23443":[2495],"vehica_23545":[2508],"vehica_6670":[4640,4542,4577,4568],"vehica_23445":[3716],"vehica_23531":[2497],"class_list":["post-32428","vehica_car","type-vehica_car","status-publish","has-post-thumbnail","hentry","vehica_23442-assetto-corsa","vehica_6659-plymouth","vehica_6660-gtx","vehica_6655-coupe","vehica_23443-traseira-rwd","vehica_23545-manual","vehica_6670-efeitos-de-pneus","vehica_6670-iluminacao-interna","vehica_6670-mapeamento-ao-completo","vehica_6670-painel-de-instrumentos-realista","vehica_23445-687-bros-company","vehica_23531-street"],"acf":{"original":"https:\/\/www.patreon.com\/posts\/687-bros-gtx-155176544","modsfire":"https:\/\/modsfire.com\/905w5893NsIM8jR","sharemods":"https:\/\/sharemods.com\/ozhmfxpcfsvd\/687_Bros_Plymouth_GTX_hemi_Gang.rar.html"},"vehica_14696":"1968","vehica_23444":"754","vehica_23446":"1034","vehica_23447":"1175","vehica_23448":"1.56","vehica_23449":"5.5","vehica_23534":"1.0","vehica_23455":"7","vehica_23456":["https:\/\/brasilsimulatormods.com\/wp-content\/uploads\/2026\/04\/687_Bros_Plymouth_GTX_hemi_Gang_Black.jpg.webp","https:\/\/brasilsimulatormods.com\/wp-content\/uploads\/2026\/04\/687_Bros_Plymouth_GTX_hemi_Gang_Deepsea_Blue.jpg.webp","https:\/\/brasilsimulatormods.com\/wp-content\/uploads\/2026\/04\/687_Bros_Plymouth_GTX_hemi_Gang_Gun_Metal.jpg.webp","https:\/\/brasilsimulatormods.com\/wp-content\/uploads\/2026\/04\/687_Bros_Plymouth_GTX_hemi_Gang_Lemon_Twist.jpg.webp","https:\/\/brasilsimulatormods.com\/wp-content\/uploads\/2026\/04\/687_Bros_Plymouth_GTX_hemi_Gang_Mood_Indigo_Metallic.jpg.webp"],"vehica_28233":"","vehica_28602":"","_links":{"self":[{"href":"https:\/\/brasilsimulatormods.com\/es\/wp-json\/wp\/v2\/cars\/32428","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/brasilsimulatormods.com\/es\/wp-json\/wp\/v2\/cars"}],"about":[{"href":"https:\/\/brasilsimulatormods.com\/es\/wp-json\/wp\/v2\/types\/vehica_car"}],"author":[{"embeddable":true,"href":"https:\/\/brasilsimulatormods.com\/es\/wp-json\/wp\/v2\/users\/1"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/brasilsimulatormods.com\/es\/wp-json\/wp\/v2\/media\/32423"}],"wp:attachment":[{"href":"https:\/\/brasilsimulatormods.com\/es\/wp-json\/wp\/v2\/media?parent=32428"}],"wp:term":[{"taxonomy":"vehica_23442","embeddable":true,"href":"https:\/\/brasilsimulatormods.com\/es\/wp-json\/wp\/v2\/vehica_23442?post=32428"},{"taxonomy":"vehica_6659","embeddable":true,"href":"https:\/\/brasilsimulatormods.com\/es\/wp-json\/wp\/v2\/vehica_6659?post=32428"},{"taxonomy":"vehica_6660","embeddable":true,"href":"https:\/\/brasilsimulatormods.com\/es\/wp-json\/wp\/v2\/vehica_6660?post=32428"},{"taxonomy":"vehica_6655","embeddable":true,"href":"https:\/\/brasilsimulatormods.com\/es\/wp-json\/wp\/v2\/vehica_6655?post=32428"},{"taxonomy":"vehica_23443","embeddable":true,"href":"https:\/\/brasilsimulatormods.com\/es\/wp-json\/wp\/v2\/vehica_23443?post=32428"},{"taxonomy":"vehica_23545","embeddable":true,"href":"https:\/\/brasilsimulatormods.com\/es\/wp-json\/wp\/v2\/vehica_23545?post=32428"},{"taxonomy":"vehica_6670","embeddable":true,"href":"https:\/\/brasilsimulatormods.com\/es\/wp-json\/wp\/v2\/vehica_6670?post=32428"},{"taxonomy":"vehica_23445","embeddable":true,"href":"https:\/\/brasilsimulatormods.com\/es\/wp-json\/wp\/v2\/vehica_23445?post=32428"},{"taxonomy":"vehica_23531","embeddable":true,"href":"https:\/\/brasilsimulatormods.com\/es\/wp-json\/wp\/v2\/vehica_23531?post=32428"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}